{"id":2032,"date":"2023-10-03T07:18:16","date_gmt":"2023-10-03T07:18:16","guid":{"rendered":"https:\/\/mdbr.it\/organizza-il-tuo-evento\/"},"modified":"2025-06-30T07:19:32","modified_gmt":"2025-06-30T07:19:32","slug":"plan-your-event","status":"publish","type":"page","link":"https:\/\/mdbr.it\/en\/plan-your-event\/","title":{"rendered":"Plan your event"},"content":{"rendered":"\n<div class=\"wp-block-group alignfull is-layout-flow wp-block-group-is-layout-flow\"><section  class=\"hero_page lg:h-[80vh] lg:min-h-[800px] relative\">\n    <div class=\"lg:absolute inset-0\">\n        <img decoding=\"async\" class=\"w-full h-auto lg:h-full lg:object-cover\" src=\"https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-pagina-organizza-un-evento.jpg\" alt=\"Un bambino gioca nel tunnel dei colori creando \">\n    <\/div>\n        <div class=\"lg:absolute inset-0 lg:flex items-center\">\n        <div class=\"container flex mx-auto px-6\">\n            <div class=\"bg-white pt-6 lg:p-7 w-full md:w-6\/12  2xl:w-5\/12 bg-opacity-90 content-wrapper\">\n               <h1><strong>PLAN YOUR CORPORATE EVENT<\/strong><\/h1>\n<p>We design and implement educational experiences for any kind of organisation<\/p>\n\n            <\/div>\n        <\/div>\n    <\/div>\n    \n   \n\n<\/section><\/div>\n\n\n\n<div style=\"height:36px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Explora is the Italian first non-profit and private Children&#8217;s Museum: since 2001, it offers a space dedicated to childhood, education and families.<\/p>\n\n\n\n<p>Specialised in the design and realisation of educational experiences for children and families, Explora constantly collaborates with companies, non-profit organisations, institutions and associations in Italy and Europe, developing educational projects and interactive exhibitions.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">What could you organise?<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"title_icon flex\">\n    <div class=\"mr-3 lg:mr-6\">\n        <div class=\"visible\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"45\" height=\"44\" viewBox=\"0 0 45 44\"><path d=\"M22,0H45a0,0,0,0,1,0,0V22A22,22,0,0,1,23,44H22A22,22,0,0,1,0,22v0A22,22,0,0,1,22,0Z\" fill=\"#bd102f\"\/><\/svg>\n        <\/div>\n    <\/div>\n    <div class=\"flex-1\">\n        <div class=\"hero-inner-blocks\">\n\n<h3 class=\"wp-block-heading title-icon\">Training Courses<\/h3>\n\n<\/div>\n    <\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"title_icon flex\">\n    <div class=\"mr-3 lg:mr-6\">\n        <div class=\"visible\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"39.743\" height=\"39.662\" viewBox=\"0 0 39.743 39.662\"><path d=\"M478.916,464.9l-5.614-5.614,5.614-5.614.045.044V439.452H464.686l-5.6,5.6-5.6-5.6H439.218v14.217l5.614,5.614-5.614,5.614v14.217h14.275l5.6-5.6,5.6,5.6h14.275V464.853Z\" transform=\"translate(-439.218 -439.452)\" fill=\"#bd102f\"\/><\/svg>\n        <\/div>\n    <\/div>\n    <div class=\"flex-1\">\n        <div class=\"hero-inner-blocks\">\n\n<h3 class=\"wp-block-heading title-icon\">Launch of new products<\/h3>\n\n<\/div>\n    <\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"title_icon flex\">\n    <div class=\"mr-3 lg:mr-6\">\n        <div class=\"visible\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"51.9\" height=\"51.9\" viewBox=\"0 0 51.9 51.9\"><path id=\"Path_1684\" data-name=\"Path 1684\" d=\"M1691.527,848.588a25.944,25.944,0,1,0,8.992,19.633c0-.505-.018-1.006-.047-1.5a13.793,13.793,0,1,1-8.945-18.128\" transform=\"translate(-1648.618 -842.271)\" fill=\"#bd102f\"\/><\/svg>\n        <\/div>\n    <\/div>\n    <div class=\"flex-1\">\n        <div class=\"hero-inner-blocks\">\n\n<h3 class=\"wp-block-heading title-icon\">Conventions<\/h3>\n\n<\/div>\n    <\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"title_icon flex\">\n    <div class=\"mr-3 lg:mr-6\">\n        <div class=\"visible\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"53.793\" height=\"53.793\" viewBox=\"0 0 53.793 53.793\"><path d=\"M446.5,50.878,439.219,43.6l7.591-7.59,5.878,5.878a19.39,19.39,0,0,0,26.881-.025l5.853-5.853,7.59,7.59L487.3,49.311a19.4,19.4,0,0,0,0,27.182l5.716,5.716-7.59,7.59-5.654-5.654a19.4,19.4,0,0,0-27.247-.055L446.809,89.8l-7.59-7.59,5.963-5.964A19.431,19.431,0,0,0,446.5,50.878\" transform=\"translate(-439.219 -36.006)\" fill=\"#be1d2d\"\/><\/svg>\n        <\/div>\n    <\/div>\n    <div class=\"flex-1\">\n        <div class=\"hero-inner-blocks\">\n\n<h3 class=\"wp-block-heading title-icon\">Book Presentation<\/h3>\n\n<\/div>\n    <\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"title_icon flex\">\n    <div class=\"mr-3 lg:mr-6\">\n        <div class=\"visible\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"45\" height=\"44\" viewBox=\"0 0 45 44\"><path d=\"M22,0H45a0,0,0,0,1,0,0V22A22,22,0,0,1,23,44H22A22,22,0,0,1,0,22v0A22,22,0,0,1,22,0Z\" fill=\"#bd102f\"\/><\/svg>\n        <\/div>\n    <\/div>\n    <div class=\"flex-1\">\n        <div class=\"hero-inner-blocks\">\n\n<h3 class=\"wp-block-heading title-icon\">Company parties<\/h3>\n\n<\/div>\n    <\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"title_icon flex\">\n    <div class=\"mr-3 lg:mr-6\">\n        <div class=\"visible\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"39.743\" height=\"39.662\" viewBox=\"0 0 39.743 39.662\"><path d=\"M478.916,464.9l-5.614-5.614,5.614-5.614.045.044V439.452H464.686l-5.6,5.6-5.6-5.6H439.218v14.217l5.614,5.614-5.614,5.614v14.217h14.275l5.6-5.6,5.6,5.6h14.275V464.853Z\" transform=\"translate(-439.218 -439.452)\" fill=\"#bd102f\"\/><\/svg>\n        <\/div>\n    <\/div>\n    <div class=\"flex-1\">\n        <div class=\"hero-inner-blocks\">\n\n<h3 class=\"wp-block-heading title-icon\">Meetings<\/h3>\n\n<\/div>\n    <\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"title_icon flex\">\n    <div class=\"mr-3 lg:mr-6\">\n        <div class=\"visible\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"51.9\" height=\"51.9\" viewBox=\"0 0 51.9 51.9\"><path id=\"Path_1684\" data-name=\"Path 1684\" d=\"M1691.527,848.588a25.944,25.944,0,1,0,8.992,19.633c0-.505-.018-1.006-.047-1.5a13.793,13.793,0,1,1-8.945-18.128\" transform=\"translate(-1648.618 -842.271)\" fill=\"#bd102f\"\/><\/svg>\n        <\/div>\n    <\/div>\n    <div class=\"flex-1\">\n        <div class=\"hero-inner-blocks\">\n\n<h2 class=\"wp-block-heading title-icon\">Show previews<\/h2>\n\n<\/div>\n    <\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"title_icon flex\">\n    <div class=\"mr-3 lg:mr-6\">\n        <div class=\"visible\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"53.793\" height=\"53.793\" viewBox=\"0 0 53.793 53.793\"><path d=\"M446.5,50.878,439.219,43.6l7.591-7.59,5.878,5.878a19.39,19.39,0,0,0,26.881-.025l5.853-5.853,7.59,7.59L487.3,49.311a19.4,19.4,0,0,0,0,27.182l5.716,5.716-7.59,7.59-5.654-5.654a19.4,19.4,0,0,0-27.247-.055L446.809,89.8l-7.59-7.59,5.963-5.964A19.431,19.431,0,0,0,446.5,50.878\" transform=\"translate(-439.219 -36.006)\" fill=\"#be1d2d\"\/><\/svg>\n        <\/div>\n    <\/div>\n    <div class=\"flex-1\">\n        <div class=\"hero-inner-blocks\">\n\n<h2 class=\"wp-block-heading title-icon\">Team building<\/h2>\n\n<\/div>\n    <\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>In addition to the attraction of its exhibition hall, characterised by large glass walls and a striking skylight that allows natural light to illuminate the interior, the museum has several additional facilities:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>a green area with inclusive and accessible games; <\/li>\n\n\n\n<li>a bookshop;<\/li>\n\n\n\n<li>a shop;<\/li>\n\n\n\n<li>a private car park.<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p>Explora&#8217;s exhibition spaces are available to host and make your event a unique experience.<\/p>\n\n\n\n<p>Contact:<a href=\"c.anguissola@mdbr.it\"> c.anguissola@mdbr.it<\/a><\/p>\n\n\n\n<p>Would you like to organise a children&#8217;s birthday party? <a href=\"https:\/\/mdbr.it\/gioca-nel-museo\/feste-di-compleanno\/\">Click here<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-the-spaces\" style=\"padding-top:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50)\">The spaces<\/h2>\n\n\n\n<div style=\"height:36px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"591\" height=\"591\" src=\"https:\/\/mdbr.it\/wp-content\/uploads\/2023\/10\/padiglione.jpg\" alt=\"foto del padiglione di Explora\" class=\"wp-image-2215\" style=\"aspect-ratio:1;object-fit:cover\" srcset=\"https:\/\/mdbr.it\/wp-content\/uploads\/2023\/10\/padiglione.jpg 591w, https:\/\/mdbr.it\/wp-content\/uploads\/2023\/10\/padiglione-300x300.jpg 300w, https:\/\/mdbr.it\/wp-content\/uploads\/2023\/10\/padiglione-450x450.jpg 450w, https:\/\/mdbr.it\/wp-content\/uploads\/2023\/10\/padiglione-500x500.jpg 500w\" sizes=\"auto, (max-width: 591px) 100vw, 591px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/mdbr.it\/wp-content\/uploads\/2023\/10\/bookshop-1024x1024.jpg\" alt=\"Immagine del bookshop del museo explora\" class=\"wp-image-2217\" style=\"aspect-ratio:1;object-fit:cover\" srcset=\"https:\/\/mdbr.it\/wp-content\/uploads\/2023\/10\/bookshop-1024x1024.jpg 1024w, https:\/\/mdbr.it\/wp-content\/uploads\/2023\/10\/bookshop-300x300.jpg 300w, https:\/\/mdbr.it\/wp-content\/uploads\/2023\/10\/bookshop-450x450.jpg 450w, https:\/\/mdbr.it\/wp-content\/uploads\/2023\/10\/bookshop-768x768.jpg 768w, https:\/\/mdbr.it\/wp-content\/uploads\/2023\/10\/bookshop-500x500.jpg 500w, https:\/\/mdbr.it\/wp-content\/uploads\/2023\/10\/bookshop.jpg 1081w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1006\" src=\"https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-open-mind-1024x1006.jpg\" alt=\"\" class=\"wp-image-7934\" style=\"aspect-ratio:1;object-fit:cover\" srcset=\"https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-open-mind-1024x1006.jpg 1024w, https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-open-mind-300x295.jpg 300w, https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-open-mind-458x450.jpg 458w, https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-open-mind-768x755.jpg 768w, https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-open-mind-1536x1509.jpg 1536w, https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-open-mind.jpg 1549w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\"><strong>Exhibition Pavilion<\/strong><\/h3>\n\n\n\n<p>Suitable for informal conferences, show previews, meetings, corporate parties, and team building. <\/p>\n\n\n\n<p>Upon request: tailor-made workshops and activities, thematic courses, interactive exhibit and play routes, and tinkering.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\"><strong>Bookshop<\/strong><\/h3>\n\n\n\n<p>Ideal for book and new product presentations, press meetings, and photo exhibitions. <\/p>\n\n\n\n<p>Upon request: tailor-made workshops and activities, readings.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\"><strong>Open Mind Space<\/strong><\/h3>\n\n\n\n<p>An exclusive space located on the ground floor. <\/p>\n\n\n\n<p>It can be reserved exclusively during the museum&#8217;s weekly closure on Mondays for the entire day, or from Tuesday to Sunday from 7:00 PM to 12:00 AM, or even during visitor hours.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"654\" height=\"654\" src=\"https:\/\/mdbr.it\/wp-content\/uploads\/2023\/10\/lab.jpg\" alt=\"\" class=\"wp-image-2221\" srcset=\"https:\/\/mdbr.it\/wp-content\/uploads\/2023\/10\/lab.jpg 654w, https:\/\/mdbr.it\/wp-content\/uploads\/2023\/10\/lab-300x300.jpg 300w, https:\/\/mdbr.it\/wp-content\/uploads\/2023\/10\/lab-450x450.jpg 450w, https:\/\/mdbr.it\/wp-content\/uploads\/2023\/10\/lab-500x500.jpg 500w\" sizes=\"auto, (max-width: 654px) 100vw, 654px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1531\" height=\"1531\" src=\"https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-giardino.jpg\" alt=\"\" class=\"wp-image-7940\" style=\"object-fit:cover;width:465px;height:465px\" srcset=\"https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-giardino.jpg 1531w, https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-giardino-300x300.jpg 300w, https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-giardino-1024x1024.jpg 1024w, https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-giardino-450x450.jpg 450w, https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-giardino-768x768.jpg 768w, https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-giardino-500x500.jpg 500w, https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-giardino-400x400.jpg 400w, https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-giardino-600x600.jpg 600w\" sizes=\"auto, (max-width: 1531px) 100vw, 1531px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1529\" height=\"1529\" src=\"https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-atrio-coperto.jpg\" alt=\"\" class=\"wp-image-7942\" style=\"width:464px;height:464px\" srcset=\"https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-atrio-coperto.jpg 1529w, https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-atrio-coperto-300x300.jpg 300w, https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-atrio-coperto-1024x1024.jpg 1024w, https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-atrio-coperto-450x450.jpg 450w, https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-atrio-coperto-768x768.jpg 768w, https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-atrio-coperto-500x500.jpg 500w, https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-atrio-coperto-400x400.jpg 400w, https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-spazio-atrio-coperto-600x600.jpg 600w\" sizes=\"auto, (max-width: 1529px) 100vw, 1529px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\"><strong>Open Lab Space<\/strong><\/h2>\n\n\n\n<p>A reserved area on the museum&#8217;s first floor, available for creative and hands-on activities. <\/p>\n\n\n\n<p>It can be exclusively opened in conjunction with the museum&#8217;s weekly closure (every Monday) for the entire day or from Tuesday to Sunday from 7:00 PM to 12:00 AM, even during visitor hours.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\"><strong>Green Area<\/strong><\/h2>\n\n\n\n<p>Ideal for show previews, new product presentations and launches, sampling, corporate parties, outdoor events, markets, street food, and photo exhibitions. <\/p>\n\n\n\n<p>Upon request: tailor-made workshops and activities, thematic courses, treasure hunts.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\"><strong>External Atrium<\/strong><\/h3>\n\n\n\n<p>Perfect for show previews, new product presentations and launches, sampling, corporate parties, outdoor events, show cooking, markets, street food. <\/p>\n\n\n\n<p>Upon request: tailor-made workshops and activities, thematic courses, treasure hunts.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:62px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Explora is the Italian first non-profit and private Children&#8217;s Museum: since 2001, it offers a space dedicated to childhood, education and families. Specialised in the design and realisation of educational experiences for children and families, Explora constantly collaborates with companies, non-profit organisations, institutions and associations in Italy and Europe, developing educational projects and interactive exhibitions. [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":7947,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2032","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Plan your event - Explora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mdbr.it\/en\/plan-your-event\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plan your event\" \/>\n<meta property=\"og:description\" content=\"Explora is the Italian first non-profit and private Children&#8217;s Museum: since 2001, it offers a space dedicated to childhood, education and families. Specialised in the design and realisation of educational experiences for children and families, Explora constantly collaborates with companies, non-profit organisations, institutions and associations in Italy and Europe, developing educational projects and interactive exhibitions. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mdbr.it\/en\/plan-your-event\/\" \/>\n<meta property=\"og:site_name\" content=\"Explora\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mdbr.it\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-30T07:19:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-pagina-organizza-un-evento.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mdbr.it\\\/en\\\/plan-your-event\\\/\",\"url\":\"https:\\\/\\\/mdbr.it\\\/en\\\/plan-your-event\\\/\",\"name\":\"Plan your event - Explora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mdbr.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mdbr.it\\\/en\\\/plan-your-event\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mdbr.it\\\/en\\\/plan-your-event\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mdbr.it\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/foto-pagina-organizza-un-evento.jpg\",\"datePublished\":\"2023-10-03T07:18:16+00:00\",\"dateModified\":\"2025-06-30T07:19:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mdbr.it\\\/en\\\/plan-your-event\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mdbr.it\\\/en\\\/plan-your-event\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mdbr.it\\\/en\\\/plan-your-event\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mdbr.it\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/foto-pagina-organizza-un-evento.jpg\",\"contentUrl\":\"https:\\\/\\\/mdbr.it\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/foto-pagina-organizza-un-evento.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Un bambino gioca nel tunnel dei colori creando\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mdbr.it\\\/en\\\/plan-your-event\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mdbr.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plan your event\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mdbr.it\\\/#website\",\"url\":\"https:\\\/\\\/mdbr.it\\\/\",\"name\":\"Explora: Il Museo dei Bambini di Roma | Attivit\u00e0 e Giochi interattivi e didattici\",\"description\":\"Scopri Explora, il Museo dei Bambini di Roma. Un ambiente interattivo dove il gioco diventa apprendimento. Scopri gli allestimenti e prenota i tuoi biglietti online!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mdbr.it\\\/#organization\"},\"alternateName\":\"Explora - Museo interattivo a Roma\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mdbr.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mdbr.it\\\/#organization\",\"name\":\"Explora - Il museo dei bambini di Roma\",\"alternateName\":\"Museo dei Bambini SCS\",\"url\":\"https:\\\/\\\/mdbr.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mdbr.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mdbr.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/explora_logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mdbr.it\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/explora_logo.jpg\",\"width\":390,\"height\":390,\"caption\":\"Explora - Il museo dei bambini di Roma\"},\"image\":{\"@id\":\"https:\\\/\\\/mdbr.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mdbr.it\\\/\",\"https:\\\/\\\/www.instagram.com\\\/museo_explora\\\/\",\"https:\\\/\\\/it.linkedin.com\\\/company\\\/explora-children-s-museum-rome\"],\"ownershipFundingInfo\":\"https:\\\/\\\/mdbr.it\\\/explora-in-chiaro\\\/\",\"actionableFeedbackPolicy\":\"https:\\\/\\\/mdbr.it\\\/chi-siamo\\\/come-si-sostiene-explora\\\/\",\"ethicsPolicy\":\"https:\\\/\\\/mdbr.it\\\/explora-in-chiaro\\\/\",\"diversityPolicy\":\"https:\\\/\\\/mdbr.it\\\/chi-siamo\\\/parita-di-genere-e-certificazioni\\\/\",\"diversityStaffingReport\":\"https:\\\/\\\/mdbr.it\\\/chi-siamo\\\/parita-di-genere-e-certificazioni\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Plan your event - Explora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mdbr.it\/en\/plan-your-event\/","og_locale":"en_US","og_type":"article","og_title":"Plan your event","og_description":"Explora is the Italian first non-profit and private Children&#8217;s Museum: since 2001, it offers a space dedicated to childhood, education and families. Specialised in the design and realisation of educational experiences for children and families, Explora constantly collaborates with companies, non-profit organisations, institutions and associations in Italy and Europe, developing educational projects and interactive exhibitions. [&hellip;]","og_url":"https:\/\/mdbr.it\/en\/plan-your-event\/","og_site_name":"Explora","article_publisher":"https:\/\/www.facebook.com\/mdbr.it\/","article_modified_time":"2025-06-30T07:19:32+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-pagina-organizza-un-evento.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mdbr.it\/en\/plan-your-event\/","url":"https:\/\/mdbr.it\/en\/plan-your-event\/","name":"Plan your event - Explora","isPartOf":{"@id":"https:\/\/mdbr.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mdbr.it\/en\/plan-your-event\/#primaryimage"},"image":{"@id":"https:\/\/mdbr.it\/en\/plan-your-event\/#primaryimage"},"thumbnailUrl":"https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-pagina-organizza-un-evento.jpg","datePublished":"2023-10-03T07:18:16+00:00","dateModified":"2025-06-30T07:19:32+00:00","breadcrumb":{"@id":"https:\/\/mdbr.it\/en\/plan-your-event\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mdbr.it\/en\/plan-your-event\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mdbr.it\/en\/plan-your-event\/#primaryimage","url":"https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-pagina-organizza-un-evento.jpg","contentUrl":"https:\/\/mdbr.it\/wp-content\/uploads\/2025\/02\/foto-pagina-organizza-un-evento.jpg","width":1920,"height":1080,"caption":"Un bambino gioca nel tunnel dei colori creando"},{"@type":"BreadcrumbList","@id":"https:\/\/mdbr.it\/en\/plan-your-event\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mdbr.it\/en\/"},{"@type":"ListItem","position":2,"name":"Plan your event"}]},{"@type":"WebSite","@id":"https:\/\/mdbr.it\/#website","url":"https:\/\/mdbr.it\/","name":"Explora: Il Museo dei Bambini di Roma | Attivit\u00e0 e Giochi interattivi e didattici","description":"Scopri Explora, il Museo dei Bambini di Roma. Un ambiente interattivo dove il gioco diventa apprendimento. Scopri gli allestimenti e prenota i tuoi biglietti online!","publisher":{"@id":"https:\/\/mdbr.it\/#organization"},"alternateName":"Explora - Museo interattivo a Roma","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mdbr.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mdbr.it\/#organization","name":"Explora - Il museo dei bambini di Roma","alternateName":"Museo dei Bambini SCS","url":"https:\/\/mdbr.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mdbr.it\/#\/schema\/logo\/image\/","url":"https:\/\/mdbr.it\/wp-content\/uploads\/2024\/07\/explora_logo.jpg","contentUrl":"https:\/\/mdbr.it\/wp-content\/uploads\/2024\/07\/explora_logo.jpg","width":390,"height":390,"caption":"Explora - Il museo dei bambini di Roma"},"image":{"@id":"https:\/\/mdbr.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mdbr.it\/","https:\/\/www.instagram.com\/museo_explora\/","https:\/\/it.linkedin.com\/company\/explora-children-s-museum-rome"],"ownershipFundingInfo":"https:\/\/mdbr.it\/explora-in-chiaro\/","actionableFeedbackPolicy":"https:\/\/mdbr.it\/chi-siamo\/come-si-sostiene-explora\/","ethicsPolicy":"https:\/\/mdbr.it\/explora-in-chiaro\/","diversityPolicy":"https:\/\/mdbr.it\/chi-siamo\/parita-di-genere-e-certificazioni\/","diversityStaffingReport":"https:\/\/mdbr.it\/chi-siamo\/parita-di-genere-e-certificazioni\/"}]}},"_links":{"self":[{"href":"https:\/\/mdbr.it\/en\/wp-json\/wp\/v2\/pages\/2032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mdbr.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mdbr.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mdbr.it\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mdbr.it\/en\/wp-json\/wp\/v2\/comments?post=2032"}],"version-history":[{"count":11,"href":"https:\/\/mdbr.it\/en\/wp-json\/wp\/v2\/pages\/2032\/revisions"}],"predecessor-version":[{"id":8912,"href":"https:\/\/mdbr.it\/en\/wp-json\/wp\/v2\/pages\/2032\/revisions\/8912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mdbr.it\/en\/wp-json\/wp\/v2\/media\/7947"}],"wp:attachment":[{"href":"https:\/\/mdbr.it\/en\/wp-json\/wp\/v2\/media?parent=2032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}